{"id":11610,"date":"2020-10-23T13:12:48","date_gmt":"2020-10-23T13:12:48","guid":{"rendered":"http:\/\/coiba.com\/?page_id=11610"},"modified":"2025-02-18T10:58:24","modified_gmt":"2025-02-18T09:58:24","slug":"ofertas-de-trabajo","status":"publish","type":"page","link":"https:\/\/infermeriabalear.com\/ca\/ofertas-de-trabajo\/","title":{"rendered":"Ofertes de Treball"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div      class=\"vc_row wpb_row section\" style=' text-align:left;'><div class=\"clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 50px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section  grid_section\" style=' text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><strong>Normativa per a les empreses que desitgin publicar les seves ofertes d\u2019ocupaci\u00f3 per a infermeres a la web del COIBA:<\/strong><\/p>\n<p>Des del COIBA vetllam per unes condicions laborals dignes per als nostres col\u00b7legiats. Volem facilitar la cerca de treball per als mateixos, per\u00f2 sempre donant espai a ofertes laborals amb condicions adequades i clares.<\/p>\n<p>&nbsp;<\/p>\n<p>Per tant, hem establert uns requisits unificats que han de complir totes les empreses que desitgin penjar la seva oferta en aquest apartat de la web. A m\u00e9s del nom de l\u2019empresa, l\u2019\u00e0rea geogr\u00e0fica i la descripci\u00f3 del lloc de treball, ser\u00e0 necessari especificar el tipus de contracte que s\u2019ofereix, les hores setmanals de treball, l\u2019\u00e0rea competencial i la remuneraci\u00f3 mensual bruta (sense prorratejar les pagues extraordin\u00e0ries).<\/p>\n<p>&nbsp;<\/p>\n<p>Recordem que, segons les taules salarials actualitzades en 2024 del<strong>\u00a0<a href=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2024\/03\/texto-articulado-nuevo-convenio-colectivo-establecimientos-sanitarios-2024-2025.pdf\" target=\"_blank\" rel=\"noopener\">Conveni Col\u00b7lectiu de Cl\u00edniques Privades de Balears,<\/a><\/strong> el salari brut m\u00ednim per a una infermera a jornada completa (mitjana setmanal de 37,45 hores) \u00e9s de 2.013,95 \u20ac, m\u00e9s dues pagues dobles de 1.555,35\u202f\u20ac. Segons les taules salarials del <strong><a href=\"https:\/\/acrobat.adobe.com\/id\/urn:aaid:sc:EU:bd679a30-3d43-4d9a-a0cd-b25a87c158c9\" target=\"_blank\" rel=\"noopener\">Conveni Col\u00b7lectiu n\u00fam. VIII, marc estatal de serveis d'atenci\u00f3 a les persones dependents,<\/a><\/strong> publicat l\u2019any 2022, el salari brut m\u00ednim per a una infermera a jornada completa \u00e9s de 1.529,71 \u20ac per l\u2019any 2024, m\u00e9s dues pagues dobles.<\/p>\n<p>&nbsp;<\/p>\n<p class=\" translation-block\">Les empreses hauran de complir amb la r\u00e0tio recomanada pel Ministerio de Sanidad, Consumo y Bienestar Social, i garantir un per\u00edode d\u2019adaptaci\u00f3 als llocs de treball amb plans d\u2019acollida.<\/p>\n<p>&nbsp;<\/p>\n<p>Si vols penjar una oferta i compleixes (o millores) les caracter\u00edstiques citades als convenis col\u00b7lectius, emplena el formulari a continuaci\u00f3.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section\" style=' text-align:left;'><div class=\"clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 30px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section  grid_section\" style=' text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><a href=\"https:\/\/infermeriabalear.com\/detalle-oferta-de-empleo-nacional\/\" target=\"_blank\" class=\"qbutton  small\" style=\"border: 1px solid #2cccd3; font-weight: 600; \">Envia una oferta de treball<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section  grid_section\" style=' text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 80px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Ofertes de Treball Auton\u00f2miques<\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 40px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class='latest_post_holder image_in_box'><ul><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/02\/49595834656_970f-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/08\/28\/arcadias-comunidad-de-propietarios-privada-busca-enfermera-o-para-mallorca-2\/\">Arcadias Comunitat de Propietaris Privada busca infermera\/r per a Mallorca<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">28 agost, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-autonomicas\/\">Ofertes de treball auton\u00f2miques <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/02\/49163165221_fcdbb0dc20_c-1-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/08\/27\/mutualidad-de-futbolistas-deleg-territorial-de-las-i-baleares-busca-enfermera-o-para-mallorca\/\">Mutualitat de Futbolistes (Deleg. Territorial de les I. Balears) busca infermera\/o per a Mallorca<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">27 agost, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-autonomicas\/\">Ofertes de treball auton\u00f2miques <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/02\/49163291282_ff3eccef28_c-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/08\/27\/mutua-universal-busca-enfermera-o-para-mallorca-3\/\">M\u00fatua Universal busca infermera\/r per a Mallorca<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">27 agost, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-autonomicas\/\">Ofertes de treball auton\u00f2miques <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/08\/Geriatria-2-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/08\/25\/fundacio-datencio-i-suport-a-la-dependencia-busca-enfermeras-ros-para-eivissa\/\">Fundaci\u00f3 d\u2019Atenci\u00f3 i Suport a la Depend\u00e8ncia busca infermeres\/rs per a Eivissa<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">25 agost, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-autonomicas\/\">Ofertes de treball auton\u00f2miques <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/03\/HEMODIALISIS-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/08\/18\/diaverum-servicios-renales-s-l-busca-enfermera-o-para-mallorca-2\/\">Diaverum Servicios Renales, S.L., busca infermera\/r per a Mallorca<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">18 agost, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-autonomicas\/\">Ofertes de treball auton\u00f2miques <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/08\/Urgencies-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/08\/07\/mutua-balear-busca-enfermera-o-urgencias-consultas-para-mallorca\/\">M\u00fatua Balear busca infermera\/r urg\u00e8ncies\/consultes per a Mallorca<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">07 agost, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-autonomicas\/\">Ofertes de treball auton\u00f2miques <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/06\/Geriatria-7-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/07\/29\/hospital-sant-joan-de-deu-busca-enfermera-o-para-mallorca-2\/\">Hospital Sant Joan de D\u00e9u busca infermera\/r per a Mallorca<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">29 juliol, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-autonomicas\/\">Ofertes de treball auton\u00f2miques <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/07\/Hospitalaria-3-1-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/07\/29\/hospital-de-llevant-busca-enfermera-para-planta-mallorca-2\/\">Hospital de Llevant busca enfermera\/o &#8211; Mallorca<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">29 juliol, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-autonomicas\/\">Ofertes de treball auton\u00f2miques <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/07\/URGENCIES-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/07\/29\/lhh-busca-enfermeras-os-para-centro-sanitario-en-palma\/\">LHH busca infermeres\/s per a centre sanitari a Palma<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">29 juliol, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-autonomicas\/\">Ofertes de treball auton\u00f2miques <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/07\/Hospitalaria-4-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/07\/27\/cell4care-busca-enfermera-o-para-iune-medical-center-palma\/\">Cell4Care busca infermera\/r per a IUNE Medical Center Palma<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">27 juliol, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-autonomicas\/\">Ofertes de treball auton\u00f2miques <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/07\/Hospitalaria-3-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/07\/15\/juaneda-hospitals-busca-enfermera-o-para-palma-mallorca\/\">Juaneda Hospitals busca infermera\/r per a Palma \u2013 Mallorca<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">15 juliol, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-autonomicas\/\">Ofertes de treball auton\u00f2miques <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/07\/Quirofan-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/07\/15\/giartd-palma-s-l-busca-enfermeras-os-para-mallorca\/\">Giartd Palma, S.L busca infermeres\/rs per a Mallorca<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">15 juliol, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-autonomicas\/\">Ofertes de treball auton\u00f2miques <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2024\/07\/49553003437_1d41811333_q.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/07\/15\/juaneda-hospitales-busca-enfermera-o-para-playa-de-muro-mallorca\/\">Juaneda Hospitals busca infermera\/r per a Platja de Muro - Mallorca<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">15 juliol, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-autonomicas\/\">Ofertes de treball auton\u00f2miques <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/06\/Quirofan-2-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/06\/02\/mutua-balear-busca-enfermera-o-para-mallorca-4\/\">M\u00fatua Balear busca infermera\/r per a Mallorca<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">02 juny, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-autonomicas\/\">Ofertes de treball auton\u00f2miques <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/06\/Hospitalaria-7-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/06\/02\/divico-consultores-busca-enfermera-o-para-mallorca-4\/\">Divico Consultors busca infermera\/r per a Mallorca<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">02 juny, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-autonomicas\/\">Ofertes de treball auton\u00f2miques <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/06\/Hospitalaria-4-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/06\/02\/divico-consultores-busca-enfermera-o-para-menorca-4\/\">Divico Consultors busca infermera\/r per a Menorca<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">02 juny, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-autonomicas\/\">Ofertes de treball auton\u00f2miques <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/05\/UCI1-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/05\/28\/divico-consultores-busca-enfermera-o-para-menorca-3\/\">Divico Consultors busca infermera\/r per a Menorca<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">28 maig, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-autonomicas\/\">Ofertes de treball auton\u00f2miques <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/05\/uci-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/05\/28\/divico-consultores-busca-enfermera-o-para-mallorca-3\/\">Divico Consultors busca infermera\/r per a Mallorca<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">28 maig, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-autonomicas\/\">Ofertes de treball auton\u00f2miques <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/05\/Geriatria-6-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/05\/25\/serveo-servicios-busca-enfermera-o-para-residencia-en-menorca\/\">Serveo Serveis busca infermera\/o per a resid\u00e8ncia a Menorca<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">25 maig, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-autonomicas\/\">Ofertes de treball auton\u00f2miques <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/05\/Quirofan-2-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/05\/21\/baviera-busca-enfermera-o-para-mallorca\/\">Baviera busca infermera\/r per a Mallorca<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">21 maig, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-autonomicas\/\">Ofertes de treball auton\u00f2miques <\/a> <\/span><\/div><\/div><\/div><\/div><\/ul><\/div><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 80px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Ofertes de Treball Nacionals<\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 40px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class='latest_post_holder image_in_box'><ul><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/06\/32054011148_40444074d6_c-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/08\/28\/hospiten-busca-enfermera-o-para-estepona-malaga\/\">Hospiten busca Infermera\/r per a Estepona \u2013 M\u00e0laga<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">28 agost, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-nacionales\/\">Ofertes de treball -Nacionals <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/08\/campament-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/08\/13\/of-experiencias-busca-enfermera-o-para-campamento-a-coruna\/\">OF experiencias busca infermera\/r per a campament \u2013 A Coru\u00f1a<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">13 agost, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-nacionales\/\">Ofertes de treball -Nacionals <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/07\/URGENCIES-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/07\/17\/fundacio-salut-emporda-busca-enfermera-o-para-urgencias-del-hospital-de-figueres-girona\/\">Fundaci\u00f3 Salut Empord\u00e0 busca infermera\/r per a urg\u00e8ncies del Hospital de Figueres \u2013 Girona<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">17 juliol, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-nacionales\/\">Ofertes de treball -Nacionals <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/06\/32054011148_40444074d6_c-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/07\/17\/fundacio-salut-emporda-busca-enfermera-o-para-hospital-en-figueres-girona\/\">Fundaci\u00f3 Salut Empord\u00e0 busca infermera\/r per a hospital en Figueres \u2013 Girona<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">17 juliol, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-nacionales\/\">Ofertes de treball -Nacionals <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/06\/Quirofan-2-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/07\/17\/fundacio-salut-emporda-busca-enfermera-o-para-el-hospital-de-figueres-girona-bloque-quirurgico\/\">Fundaci\u00f3 Salut Empord\u00e0 busca infermera\/r para el Hospital de Figueres \u2013 Girona (Bloc Quir\u00fargic)<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">17 juliol, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-nacionales\/\">Ofertes de treball -Nacionals <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/04\/Quirofan-2-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/04\/30\/facexpert-clinic-s-l-busca-enfermeras-os-para-quirofano\/\">Facexpert Clinic, S.L. busca infermeres\/rs per a quir\u00f2fan<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">30 abril, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-nacionales\/\">Ofertes de treball -Nacionals <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2025\/11\/32054011148_40444074d6_q.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/03\/16\/orden-hospitalaria-san-juan-de-dios-hospital-santa-clotilde-santander-busca-enfermeras-os\/\">Orden Hospitalaria San Juan de Dios \u2013 Hospital Santa Clotilde \u2013 Santander busca infermeres\/rs<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">16 mar\u00e7, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-nacionales\/\">Ofertes de treball -Nacionals <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/02\/URGENCIES-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/02\/25\/hospital-ribera-juan-cardona-busca-enfermeras-os-para-ferrol-a-coruna\/\">Hospital Ribera Juan Cardona busca infermeres\/rs per a Ferrol \u2013 A Coru\u00f1a<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">25 febrer, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas_empleo-nacionales\/\">Ofertes de treball -Nacionals <\/a> <\/span><\/div><\/div><\/div><\/div><\/ul><\/div><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section  grid_section\" style=' text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 40px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Cooperaci\u00f3 i voluntariat<\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 40px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class='latest_post_holder image_in_box'><ul><\/ul><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 40px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Ofertes de Treball Internacionals<\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 40px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class='latest_post_holder image_in_box'><ul><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/05\/45903372072_65a8ced570_z-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/07\/15\/precise-busca-enfermera-o-para-suiza\/\">Precise busca infermera\/r per a Su\u00efssa<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">15 juliol, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas-de-empleo-inter\/\">Ofertes de treball-Internacionals <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/01\/uci-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/07\/15\/precise-busca-enfermeras-os-para-francia-3\/\">Precise busca infermeres\/s per a Fran\u00e7a<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">15 juliol, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas-de-empleo-inter\/\">Ofertes de treball-Internacionals <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/06\/Geriatria-1-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/06\/03\/helebemanning-slu-busca-enfermeras-os-para-residencias-en-irlanda\/\">Helebemanning, SLU busca infermeras\/rs per a resid\u00e8ncies a Irlanda<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">03 juny, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas-de-empleo-inter\/\">Ofertes de treball-Internacionals <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2025\/01\/49596082712_0875e40b89_q.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/05\/27\/global-working-busca-enfermeras-os-para-brujas-belgica\/\">Global  Working busca infermera\/r per a Bruges - B\u00e8lgica<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">27 maig, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas-de-empleo-inter\/\">Ofertes de treball-Internacionals <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/05\/45903372072_65a8ced570_z-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/05\/04\/precise-busca-enfermeras-os-para-alemania\/\">Precise busca infermeres\/s per a Alemanya<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">04 maig, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas-de-empleo-inter\/\">Ofertes de treball-Internacionals <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/04\/32054011148_40444074d6_c-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/04\/30\/global-working-busca-enfermera-o-para-belgica\/\">Global  Working busca infermera\/r per a B\u00e8lgica<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">30 abril, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas-de-empleo-inter\/\">Ofertes de treball-Internacionals <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/03\/Hospitalaria-3-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/03\/27\/global-working-busca-enfermeras-os-para-alemania\/\">Global  Working busca infermeres\/rs per a Alemania<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">27 mar\u00e7, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas-de-empleo-inter\/\">Ofertes de treball-Internacionals <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/03\/42133533950_f06baaacd8_s-1.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/03\/27\/global-working-busca-enfermeras-os-para-noruega\/\">Global  Working busca infermeres\/rs per a Noruega<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">27 mar\u00e7, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas-de-empleo-inter\/\">Ofertes de treball-Internacionals <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/03\/Quirofan-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/03\/18\/appel-medical-busca-enfermeras-os-de-quirofano-para-hospital-publico-en-estrasburgo-francia\/\">Appel M\u00e9dical busca infermeres\/rs de quir\u00f2fan per a hospital p\u00fablic a Estrasburg - Fran\u00e7a<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">18 mar\u00e7, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas-de-empleo-inter\/\">Ofertes de treball-Internacionals <\/a> <\/span><\/div><\/div><\/div><\/div><li class=\"clearfix\"><div class=\"latest_post\"><div class=\"latest_post_image clearfix\"><img decoding=\"async\" src=\"https:\/\/infermeriabalear.com\/wp-content\/uploads\/2026\/03\/UCI1-150x150.jpg\" alt=\"\" \/><\/div><div class=\"latest_post_text\"><div class=\"latest_post_inner\"><div class=\"latest_post_text_inner\"><h4 class=\"latest_post_title\"><a href=\"https:\/\/infermeriabalear.com\/ca\/2026\/03\/13\/precise-busca-enfermeras-os-para-francia\/\">Precise busca infermeres\/s per a Fran\u00e7a<\/a><\/h4><span class=\"post_infos\"><span class=\"date_hour_holder\"><i class=\"fa fa-calendar-o\"><\/i><span class=\"date\">13 mar\u00e7, 2026<\/span><\/span><span class=\"latest-vert-separator\"> in<\/span> <a href=\"https:\/\/infermeriabalear.com\/ca\/category\/ofertas-de-empleo-inter\/\">Ofertes de treball-Internacionals <\/a> <\/span><\/div><\/div><\/div><\/div><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section  grid_section\" style=' text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section\" style=' text-align:left;'><div class=\"clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Precise (Centro dependiente de la administraci\u00f3n p\u00fablica) &nbsp; Lugar de trabajo: Francia (Hospitales, cl\u00ednicas y centros multidisciplinarios) \u00c1mbito: Generalista Sueldo...","protected":false},"author":9,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"footnotes":""},"class_list":["post-11610","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/infermeriabalear.com\/ca\/wp-json\/wp\/v2\/pages\/11610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infermeriabalear.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/infermeriabalear.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/infermeriabalear.com\/ca\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/infermeriabalear.com\/ca\/wp-json\/wp\/v2\/comments?post=11610"}],"version-history":[{"count":6,"href":"https:\/\/infermeriabalear.com\/ca\/wp-json\/wp\/v2\/pages\/11610\/revisions"}],"predecessor-version":[{"id":42072,"href":"https:\/\/infermeriabalear.com\/ca\/wp-json\/wp\/v2\/pages\/11610\/revisions\/42072"}],"wp:attachment":[{"href":"https:\/\/infermeriabalear.com\/ca\/wp-json\/wp\/v2\/media?parent=11610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}